{"id":39961,"date":"2026-05-12T14:15:52","date_gmt":"2026-05-12T12:15:52","guid":{"rendered":"https:\/\/srfb.be\/?post_type=srfb-formations&#038;p=39961"},"modified":"2026-05-12T14:15:52","modified_gmt":"2026-05-12T12:15:52","slug":"balade-bourgeons-2026","status":"publish","type":"srfb-formations","link":"https:\/\/kbbm.be\/nl\/formations\/balade-bourgeons-2026\/","title":{"rendered":"Ontdekking van boom- en struikknoppen en hun toepassingen in de fytotherapie (gemmotherapie)"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Het bos is een prachtige bron van gezondheid. Er zijn veel planten, paddenstoelen, bomen en struiken, traditionele remedies in de fytotherapie en meer recente ontdekkingen zoals gemmotherapie, waarbij knoppen van bomen en struiken worden gebruikt als remedies.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au printemps, la for\u00eat se r\u00e9veille et nous offre son renouveau : jeunes plantes foresti\u00e8res, s\u00e8ve de bouleau et bourgeons, \u00e0 d\u00e9couvrir&#8230;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De Koninklijke Belgische Bosbouwmaatschappij (KBBM) is een non-profitorganisatie die zich inzet voor het bos en bosbouwers. Haar Forest Friends-projecten zijn gericht op het grote publiek dat de bosomgeving wil leren kennen. De vrijwillige bosgidsen van de KBBM helpen je het bos te ontdekken als bron van leven, in nauw contact met de mens.<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"font-style:normal;font-weight:700\">Inscription obligatoire au plus tard le\u00a021 mars\u00a0aupr\u00e8s de la guide au\u00a00476\/ 21 43 30\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>La for\u00eat est une magnifique ressource pour la sant\u00e9. On y trouve de nombreuses plantes, champignons, arbres et arbustes, rem\u00e8des traditionnels en phytoth\u00e9rapie, et des d\u00e9couvertes plus r\u00e9centes comme la gemmoth\u00e9rapie qui utilise les bourgeons d&rsquo;arbres et d&rsquo;arbustes en tant que rem\u00e8des.&nbsp; Au printemps, la for\u00eat se r\u00e9veille et nous offre son renouveau : jeunes&#8230; <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/kbbm.be\/nl\/formations\/balade-bourgeons-2026\/\" class=\"excerpt-read-more\">Meer lezen<\/a><\/p>","protected":false},"author":18,"featured_media":38165,"parent":0,"template":"","meta":[],"event-types":[821],"event-languages":[816],"srfb-formations-taxonomy":[835],"class_list":["post-39961","srfb-formations","type-srfb-formations","status-publish","has-post-thumbnail","hentry","event-types-balade-guidee","event-languages-francais","srfb-formations-taxonomy-forest-friends"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c0 la d\u00e9couverte des bourgeons d&#039;arbres et d&#039;arbustes et leurs usages en phytoth\u00e9rapie (gemmoth\u00e9rapie) - Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kbbm.be\/nl\/formations\/balade-bourgeons-2026\/\" \/>\n<meta property=\"og:locale\" content=\"nl_BE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c0 la d\u00e9couverte des bourgeons d&#039;arbres et d&#039;arbustes et leurs usages en phytoth\u00e9rapie (gemmoth\u00e9rapie) - Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique\" \/>\n<meta property=\"og:description\" content=\"La for\u00eat est une magnifique ressource pour la sant\u00e9. On y trouve de nombreuses plantes, champignons, arbres et arbustes, rem\u00e8des traditionnels en phytoth\u00e9rapie, et des d\u00e9couvertes plus r\u00e9centes comme la gemmoth\u00e9rapie qui utilise les bourgeons d&rsquo;arbres et d&rsquo;arbustes en tant que rem\u00e8des.&nbsp; Au printemps, la for\u00eat se r\u00e9veille et nous offre son renouveau : jeunes... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kbbm.be\/nl\/formations\/balade-bourgeons-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/srfb.be\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kbbm.be\/wp-content\/uploads\/2025\/03\/bourgeon.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kbbm.be\\\/nl\\\/formations\\\/balade-bourgeons-2026\\\/\",\"url\":\"https:\\\/\\\/www.kbbm.be\\\/nl\\\/formations\\\/balade-bourgeons-2026\\\/\",\"name\":\"\u00c0 la d\u00e9couverte des bourgeons d'arbres et d'arbustes et leurs usages en phytoth\u00e9rapie (gemmoth\u00e9rapie) - Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/srfb.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kbbm.be\\\/nl\\\/formations\\\/balade-bourgeons-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kbbm.be\\\/nl\\\/formations\\\/balade-bourgeons-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kbbm.be\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/bourgeon.jpg\",\"datePublished\":\"2026-05-12T12:15:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kbbm.be\\\/nl\\\/formations\\\/balade-bourgeons-2026\\\/#breadcrumb\"},\"inLanguage\":\"nl-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kbbm.be\\\/nl\\\/formations\\\/balade-bourgeons-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-BE\",\"@id\":\"https:\\\/\\\/www.kbbm.be\\\/nl\\\/formations\\\/balade-bourgeons-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kbbm.be\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/bourgeon.jpg\",\"contentUrl\":\"https:\\\/\\\/kbbm.be\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/bourgeon.jpg\",\"width\":1280,\"height\":853,\"caption\":\"Bourgeon prunellier bourbier\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kbbm.be\\\/nl\\\/formations\\\/balade-bourgeons-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/srfb.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c0 la d\u00e9couverte des bourgeons d&rsquo;arbres et d&rsquo;arbustes et leurs usages en phytoth\u00e9rapie (gemmoth\u00e9rapie)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/srfb.be\\\/#website\",\"url\":\"https:\\\/\\\/srfb.be\\\/\",\"name\":\"Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique\",\"description\":\"Au service de la for\u00eat et des forestiers\",\"publisher\":{\"@id\":\"https:\\\/\\\/srfb.be\\\/#organization\"},\"alternateName\":\"SRFB-KBBM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/srfb.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-BE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/srfb.be\\\/#organization\",\"name\":\"Soci\u00e9t\u00e9 Royale Foresti\u00e8re De Belgique - Koninklijke Belgische Bosbouwmaatschappij\",\"alternateName\":\"SRFB-KBBM\",\"url\":\"https:\\\/\\\/srfb.be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-BE\",\"@id\":\"https:\\\/\\\/srfb.be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/srfb.be\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/android-chrome-256x256.png\",\"contentUrl\":\"https:\\\/\\\/srfb.be\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/android-chrome-256x256.png\",\"width\":1200,\"height\":1232,\"caption\":\"Soci\u00e9t\u00e9 Royale Foresti\u00e8re De Belgique - Koninklijke Belgische Bosbouwmaatschappij\"},\"image\":{\"@id\":\"https:\\\/\\\/srfb.be\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/srfb.be\",\"https:\\\/\\\/www.instagram.com\\\/srfb_kbbm\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/srfb-kbbm\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/srfbkbbm\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Op ontdekking met boom- en struikknopjes en hun gebruik in de fytotherapie (gemmotherapie) - Koninklijke Belgische Bosbouwmaatschappij","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kbbm.be\/nl\/formations\/balade-bourgeons-2026\/","og_locale":"nl_BE","og_type":"article","og_title":"\u00c0 la d\u00e9couverte des bourgeons d'arbres et d'arbustes et leurs usages en phytoth\u00e9rapie (gemmoth\u00e9rapie) - Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique","og_description":"La for\u00eat est une magnifique ressource pour la sant\u00e9. On y trouve de nombreuses plantes, champignons, arbres et arbustes, rem\u00e8des traditionnels en phytoth\u00e9rapie, et des d\u00e9couvertes plus r\u00e9centes comme la gemmoth\u00e9rapie qui utilise les bourgeons d&rsquo;arbres et d&rsquo;arbustes en tant que rem\u00e8des.&nbsp; Au printemps, la for\u00eat se r\u00e9veille et nous offre son renouveau : jeunes... Read More","og_url":"https:\/\/www.kbbm.be\/nl\/formations\/balade-bourgeons-2026\/","og_site_name":"Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique","article_publisher":"https:\/\/www.facebook.com\/srfb.be","og_image":[{"width":1280,"height":853,"url":"https:\/\/www.kbbm.be\/wp-content\/uploads\/2025\/03\/bourgeon.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.kbbm.be\/nl\/formations\/balade-bourgeons-2026\/","url":"https:\/\/www.kbbm.be\/nl\/formations\/balade-bourgeons-2026\/","name":"Op ontdekking met boom- en struikknopjes en hun gebruik in de fytotherapie (gemmotherapie) - Koninklijke Belgische Bosbouwmaatschappij","isPartOf":{"@id":"https:\/\/srfb.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kbbm.be\/nl\/formations\/balade-bourgeons-2026\/#primaryimage"},"image":{"@id":"https:\/\/www.kbbm.be\/nl\/formations\/balade-bourgeons-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/kbbm.be\/wp-content\/uploads\/2025\/03\/bourgeon.jpg","datePublished":"2026-05-12T12:15:52+00:00","breadcrumb":{"@id":"https:\/\/www.kbbm.be\/nl\/formations\/balade-bourgeons-2026\/#breadcrumb"},"inLanguage":"nl-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kbbm.be\/nl\/formations\/balade-bourgeons-2026\/"]}]},{"@type":"ImageObject","inLanguage":"nl-BE","@id":"https:\/\/www.kbbm.be\/nl\/formations\/balade-bourgeons-2026\/#primaryimage","url":"https:\/\/kbbm.be\/wp-content\/uploads\/2025\/03\/bourgeon.jpg","contentUrl":"https:\/\/kbbm.be\/wp-content\/uploads\/2025\/03\/bourgeon.jpg","width":1280,"height":853,"caption":"Bourgeon prunellier bourbier"},{"@type":"BreadcrumbList","@id":"https:\/\/www.kbbm.be\/nl\/formations\/balade-bourgeons-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/srfb.be\/"},{"@type":"ListItem","position":2,"name":"\u00c0 la d\u00e9couverte des bourgeons d&rsquo;arbres et d&rsquo;arbustes et leurs usages en phytoth\u00e9rapie (gemmoth\u00e9rapie)"}]},{"@type":"WebSite","@id":"https:\/\/srfb.be\/#website","url":"https:\/\/srfb.be\/","name":"Koninklijke Belgische Bosbouwmaatschappij","description":"Ten dienste van het bos en de bosbouwers","publisher":{"@id":"https:\/\/srfb.be\/#organization"},"alternateName":"SRFB-KBBM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/srfb.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-BE"},{"@type":"Organization","@id":"https:\/\/srfb.be\/#organization","name":"Soci\u00e9t\u00e9 Royale Foresti\u00e8re De Belgique - Koninklijke Belgische Bosbouwmaatschappij","alternateName":"SRFB-KBBM","url":"https:\/\/srfb.be\/","logo":{"@type":"ImageObject","inLanguage":"nl-BE","@id":"https:\/\/srfb.be\/#\/schema\/logo\/image\/","url":"https:\/\/srfb.be\/wp-content\/uploads\/2019\/06\/android-chrome-256x256.png","contentUrl":"https:\/\/srfb.be\/wp-content\/uploads\/2019\/06\/android-chrome-256x256.png","width":1200,"height":1232,"caption":"Soci\u00e9t\u00e9 Royale Foresti\u00e8re De Belgique - Koninklijke Belgische Bosbouwmaatschappij"},"image":{"@id":"https:\/\/srfb.be\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/srfb.be","https:\/\/www.instagram.com\/srfb_kbbm\/","https:\/\/www.linkedin.com\/company\/srfb-kbbm\/","https:\/\/www.youtube.com\/user\/srfbkbbm"]}]}},"_links":{"self":[{"href":"https:\/\/kbbm.be\/nl\/wp-json\/wp\/v2\/srfb-formations\/39961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kbbm.be\/nl\/wp-json\/wp\/v2\/srfb-formations"}],"about":[{"href":"https:\/\/kbbm.be\/nl\/wp-json\/wp\/v2\/types\/srfb-formations"}],"author":[{"embeddable":true,"href":"https:\/\/kbbm.be\/nl\/wp-json\/wp\/v2\/users\/18"}],"wp:attachment":[{"href":"https:\/\/kbbm.be\/nl\/wp-json\/wp\/v2\/media?parent=39961"}],"wp:term":[{"taxonomy":"event-types","embeddable":true,"href":"https:\/\/kbbm.be\/nl\/wp-json\/wp\/v2\/event-types?post=39961"},{"taxonomy":"event-languages","embeddable":true,"href":"https:\/\/kbbm.be\/nl\/wp-json\/wp\/v2\/event-languages?post=39961"},{"taxonomy":"srfb-formations-taxonomy","embeddable":true,"href":"https:\/\/kbbm.be\/nl\/wp-json\/wp\/v2\/srfb-formations-taxonomy?post=39961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}