{"id":40064,"date":"2026-05-19T14:19:22","date_gmt":"2026-05-19T12:19:22","guid":{"rendered":"https:\/\/srfb.be\/?post_type=srfb-formations&#038;p=40064"},"modified":"2026-05-19T14:27:54","modified_gmt":"2026-05-19T12:27:54","slug":"prevenir-plutot-que-subir-tout-savoir-sur-lassurance-collective-rc-foret-et-les-bonnes-pratiques-forestieres","status":"publish","type":"srfb-formations","link":"https:\/\/kbbm.be\/en\/formations\/prevenir-plutot-que-subir-tout-savoir-sur-lassurance-collective-rc-foret-et-les-bonnes-pratiques-forestieres\/","title":{"rendered":"Prevention rather than suffering: Everything you need to know about group \u00abForest Liability\u00bb insurance and good forestry practice \u00bb"},"content":{"rendered":"<h3 class=\"wp-block-heading\">Objective<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">As a forest owner, in certain situations provided for by law, you may be held civilly liable for damage caused by your trees to third parties. Risk prevention and a good understanding of the general framework of coverage are therefore essential.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">During this webinar, we will clarify the concept of forest owner civil liability and explain how the \u00abRC For\u00eat\u00bb collective insurance scheme, for which SRFB is the policyholder, works. This scheme is included in the Premium contribution of SRFB members. SRFB members benefit from the coverage provided by this collective policy without needing to enter into an individual contract with the insurer. We will examine a few practical cases for illustrative purposes. Secondly, as the best insurance is prevention, we will highlight best practices that will enable you to minimise risks (regular visual inspections, preventive pruning and felling, path maintenance, public information, etc.). Finally, we will cover the procedure to follow in the event of a claim. Here again, we will illustrate with real-life cases.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Ce webinaire est organis\u00e9 \u00e0 des fins d\u2019information g\u00e9n\u00e9rale.&nbsp;Les informations communiqu\u00e9es ne constituent ni un avis juridique personnalis\u00e9, ni une offre ou une proposition de contrat d\u2019assurance individuelle.&nbsp;La gestion des contrats et des sinistres est assur\u00e9e par le courtier de la SRFB, en collaboration avec la compagnie d\u2019assurance<\/em>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Speakers<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Philippe de Wouters<\/strong>, RFSB<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Program<\/strong><\/h3>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong>20h00<\/strong><\/td><td class=\"has-text-align-left\" data-align=\"left\">Introduction and objectives of the webinar<\/td><\/tr><tr><td><strong>20:10<\/strong><\/td><td class=\"has-text-align-left\" data-align=\"left\">Presentation of the general framework for the SRFB's \u00abForest Third-Party Liability\u00bb collective insurance<\/td><\/tr><tr><td><strong>8:25 PM<\/strong><\/td><td class=\"has-text-align-left\" data-align=\"left\">Pr\u00e9vention&nbsp;et bonnes pratiques&nbsp;au&nbsp;quotidien :&nbsp;R\u00f4le du propri\u00e9taire&nbsp;forestier<\/td><\/tr><tr><td><strong>8:55 PM<\/strong><\/td><td class=\"has-text-align-left\" data-align=\"left\">Que faire en cas de sinistre\u202f?&nbsp;R\u00f4le du courtier et proc\u00e9dure pratique&nbsp;<\/td><\/tr><tr><td><strong>21:05<\/strong><\/td><td class=\"has-text-align-left\" data-align=\"left\">Questions-answers and conclusion<\/td><\/tr><\/tbody><\/table><\/figure>","protected":false},"excerpt":{"rendered":"<p>Objectif En tant que propri\u00e9taire forestier, vous pouvez, dans certaines situations pr\u00e9vues par la loi, voir votre responsabilit\u00e9 civile engag\u00e9e en cas de dommages caus\u00e9s par vos arbres \u00e0 des tiers. La pr\u00e9vention des risques et une bonne compr\u00e9hension du cadre g\u00e9n\u00e9ral de couverture sont d\u00e8s lors essentielles.&nbsp;&nbsp; Au cours de ce webinaire, nous pr\u00e9ciserons&#8230; <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/kbbm.be\/en\/formations\/prevenir-plutot-que-subir-tout-savoir-sur-lassurance-collective-rc-foret-et-les-bonnes-pratiques-forestieres\/\" class=\"excerpt-read-more\">Read More<\/a><\/p>","protected":false},"author":18,"featured_media":22247,"parent":0,"template":"","meta":[],"event-types":[829],"event-languages":[816],"srfb-formations-taxonomy":[839],"class_list":["post-40064","srfb-formations","type-srfb-formations","status-publish","has-post-thumbnail","hentry","event-types-webinaire","event-languages-francais","srfb-formations-taxonomy-vulgarisation"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pr\u00e9venir plut\u00f4t que subir\u00a0: Tout savoir sur l\u2019assurance collective \u00ab\u00a0RC\u00a0For\u00eat\u00a0\u00bb et \u00ab\u00a0les\u00a0bonnes pratiques foresti\u00e8res\u00a0\u00bb - Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/srfb.be\/nl\/formations\/prevenir-plutot-que-subir-tout-savoir-sur-lassurance-collective-rc-foret-et-les-bonnes-pratiques-forestieres\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pr\u00e9venir plut\u00f4t que subir\u00a0: Tout savoir sur l\u2019assurance collective \u00ab\u00a0RC\u00a0For\u00eat\u00a0\u00bb et \u00ab\u00a0les\u00a0bonnes pratiques foresti\u00e8res\u00a0\u00bb - Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique\" \/>\n<meta property=\"og:description\" content=\"Objectif En tant que propri\u00e9taire forestier, vous pouvez, dans certaines situations pr\u00e9vues par la loi, voir votre responsabilit\u00e9 civile engag\u00e9e en cas de dommages caus\u00e9s par vos arbres \u00e0 des tiers. La pr\u00e9vention des risques et une bonne compr\u00e9hension du cadre g\u00e9n\u00e9ral de couverture sont d\u00e8s lors essentielles.&nbsp;&nbsp; Au cours de ce webinaire, nous pr\u00e9ciserons... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/srfb.be\/nl\/formations\/prevenir-plutot-que-subir-tout-savoir-sur-lassurance-collective-rc-foret-et-les-bonnes-pratiques-forestieres\/\" \/>\n<meta property=\"og:site_name\" content=\"Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/srfb.be\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-19T12:27:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/srfb.be\/wp-content\/uploads\/2022\/02\/accident-rotated.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1748\" \/>\n\t<meta property=\"og:image:height\" content=\"1240\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/srfb.be\\\/nl\\\/formations\\\/prevenir-plutot-que-subir-tout-savoir-sur-lassurance-collective-rc-foret-et-les-bonnes-pratiques-forestieres\\\/\",\"url\":\"https:\\\/\\\/srfb.be\\\/nl\\\/formations\\\/prevenir-plutot-que-subir-tout-savoir-sur-lassurance-collective-rc-foret-et-les-bonnes-pratiques-forestieres\\\/\",\"name\":\"Pr\u00e9venir plut\u00f4t que subir\u00a0: Tout savoir sur l\u2019assurance collective \u00ab\u00a0RC\u00a0For\u00eat\u00a0\u00bb et \u00ab\u00a0les\u00a0bonnes pratiques foresti\u00e8res\u00a0\u00bb - Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/srfb.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/srfb.be\\\/nl\\\/formations\\\/prevenir-plutot-que-subir-tout-savoir-sur-lassurance-collective-rc-foret-et-les-bonnes-pratiques-forestieres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/srfb.be\\\/nl\\\/formations\\\/prevenir-plutot-que-subir-tout-savoir-sur-lassurance-collective-rc-foret-et-les-bonnes-pratiques-forestieres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kbbm.be\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/accident-rotated.jpg\",\"datePublished\":\"2026-05-19T12:19:22+00:00\",\"dateModified\":\"2026-05-19T12:27:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/srfb.be\\\/nl\\\/formations\\\/prevenir-plutot-que-subir-tout-savoir-sur-lassurance-collective-rc-foret-et-les-bonnes-pratiques-forestieres\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/srfb.be\\\/nl\\\/formations\\\/prevenir-plutot-que-subir-tout-savoir-sur-lassurance-collective-rc-foret-et-les-bonnes-pratiques-forestieres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/srfb.be\\\/nl\\\/formations\\\/prevenir-plutot-que-subir-tout-savoir-sur-lassurance-collective-rc-foret-et-les-bonnes-pratiques-forestieres\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kbbm.be\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/accident-rotated.jpg\",\"contentUrl\":\"https:\\\/\\\/kbbm.be\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/accident-rotated.jpg\",\"width\":1748,\"height\":1240,\"caption\":\"Voiture accident\u00e9e avec un arbre - RC For\u00eat\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/srfb.be\\\/nl\\\/formations\\\/prevenir-plutot-que-subir-tout-savoir-sur-lassurance-collective-rc-foret-et-les-bonnes-pratiques-forestieres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/srfb.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pr\u00e9venir plut\u00f4t que subir\u00a0: Tout savoir sur l\u2019assurance collective \u00ab\u00a0RC\u00a0For\u00eat\u00a0\u00bb et \u00ab\u00a0les\u00a0bonnes pratiques foresti\u00e8res\u00a0\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/srfb.be\\\/#website\",\"url\":\"https:\\\/\\\/srfb.be\\\/\",\"name\":\"Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique\",\"description\":\"Au service de la for\u00eat et des forestiers\",\"publisher\":{\"@id\":\"https:\\\/\\\/srfb.be\\\/#organization\"},\"alternateName\":\"SRFB-KBBM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/srfb.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/srfb.be\\\/#organization\",\"name\":\"Soci\u00e9t\u00e9 Royale Foresti\u00e8re De Belgique - Koninklijke Belgische Bosbouwmaatschappij\",\"alternateName\":\"SRFB-KBBM\",\"url\":\"https:\\\/\\\/srfb.be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/srfb.be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/srfb.be\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/android-chrome-256x256.png\",\"contentUrl\":\"https:\\\/\\\/srfb.be\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/android-chrome-256x256.png\",\"width\":1200,\"height\":1232,\"caption\":\"Soci\u00e9t\u00e9 Royale Foresti\u00e8re De Belgique - Koninklijke Belgische Bosbouwmaatschappij\"},\"image\":{\"@id\":\"https:\\\/\\\/srfb.be\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/srfb.be\",\"https:\\\/\\\/www.instagram.com\\\/srfb_kbbm\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/srfb-kbbm\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/srfbkbbm\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prevention rather than cure: All you need to know about \u00abRC_Forest\u00bb collective insurance and \u00abgood forestry practices\u00bb - Royal Belgian Forestry Society","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/srfb.be\/nl\/formations\/prevenir-plutot-que-subir-tout-savoir-sur-lassurance-collective-rc-foret-et-les-bonnes-pratiques-forestieres\/","og_locale":"en_GB","og_type":"article","og_title":"Pr\u00e9venir plut\u00f4t que subir\u00a0: Tout savoir sur l\u2019assurance collective \u00ab\u00a0RC\u00a0For\u00eat\u00a0\u00bb et \u00ab\u00a0les\u00a0bonnes pratiques foresti\u00e8res\u00a0\u00bb - Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique","og_description":"Objectif En tant que propri\u00e9taire forestier, vous pouvez, dans certaines situations pr\u00e9vues par la loi, voir votre responsabilit\u00e9 civile engag\u00e9e en cas de dommages caus\u00e9s par vos arbres \u00e0 des tiers. La pr\u00e9vention des risques et une bonne compr\u00e9hension du cadre g\u00e9n\u00e9ral de couverture sont d\u00e8s lors essentielles.&nbsp;&nbsp; Au cours de ce webinaire, nous pr\u00e9ciserons... Read More","og_url":"https:\/\/srfb.be\/nl\/formations\/prevenir-plutot-que-subir-tout-savoir-sur-lassurance-collective-rc-foret-et-les-bonnes-pratiques-forestieres\/","og_site_name":"Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique","article_publisher":"https:\/\/www.facebook.com\/srfb.be","article_modified_time":"2026-05-19T12:27:54+00:00","og_image":[{"width":1748,"height":1240,"url":"https:\/\/srfb.be\/wp-content\/uploads\/2022\/02\/accident-rotated.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/srfb.be\/nl\/formations\/prevenir-plutot-que-subir-tout-savoir-sur-lassurance-collective-rc-foret-et-les-bonnes-pratiques-forestieres\/","url":"https:\/\/srfb.be\/nl\/formations\/prevenir-plutot-que-subir-tout-savoir-sur-lassurance-collective-rc-foret-et-les-bonnes-pratiques-forestieres\/","name":"Prevention rather than cure: All you need to know about \u00abRC_Forest\u00bb collective insurance and \u00abgood forestry practices\u00bb - Royal Belgian Forestry Society","isPartOf":{"@id":"https:\/\/srfb.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/srfb.be\/nl\/formations\/prevenir-plutot-que-subir-tout-savoir-sur-lassurance-collective-rc-foret-et-les-bonnes-pratiques-forestieres\/#primaryimage"},"image":{"@id":"https:\/\/srfb.be\/nl\/formations\/prevenir-plutot-que-subir-tout-savoir-sur-lassurance-collective-rc-foret-et-les-bonnes-pratiques-forestieres\/#primaryimage"},"thumbnailUrl":"https:\/\/kbbm.be\/wp-content\/uploads\/2022\/02\/accident-rotated.jpg","datePublished":"2026-05-19T12:19:22+00:00","dateModified":"2026-05-19T12:27:54+00:00","breadcrumb":{"@id":"https:\/\/srfb.be\/nl\/formations\/prevenir-plutot-que-subir-tout-savoir-sur-lassurance-collective-rc-foret-et-les-bonnes-pratiques-forestieres\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/srfb.be\/nl\/formations\/prevenir-plutot-que-subir-tout-savoir-sur-lassurance-collective-rc-foret-et-les-bonnes-pratiques-forestieres\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/srfb.be\/nl\/formations\/prevenir-plutot-que-subir-tout-savoir-sur-lassurance-collective-rc-foret-et-les-bonnes-pratiques-forestieres\/#primaryimage","url":"https:\/\/kbbm.be\/wp-content\/uploads\/2022\/02\/accident-rotated.jpg","contentUrl":"https:\/\/kbbm.be\/wp-content\/uploads\/2022\/02\/accident-rotated.jpg","width":1748,"height":1240,"caption":"Voiture accident\u00e9e avec un arbre - RC For\u00eat"},{"@type":"BreadcrumbList","@id":"https:\/\/srfb.be\/nl\/formations\/prevenir-plutot-que-subir-tout-savoir-sur-lassurance-collective-rc-foret-et-les-bonnes-pratiques-forestieres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/srfb.be\/"},{"@type":"ListItem","position":2,"name":"Pr\u00e9venir plut\u00f4t que subir\u00a0: Tout savoir sur l\u2019assurance collective \u00ab\u00a0RC\u00a0For\u00eat\u00a0\u00bb et \u00ab\u00a0les\u00a0bonnes pratiques foresti\u00e8res\u00a0\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/srfb.be\/#website","url":"https:\/\/srfb.be\/","name":"Royal Forestry Society of Belgium","description":"Serving forests and foresters","publisher":{"@id":"https:\/\/srfb.be\/#organization"},"alternateName":"SRFB-KBBM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/srfb.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/srfb.be\/#organization","name":"Soci\u00e9t\u00e9 Royale Foresti\u00e8re De Belgique - Koninklijke Belgische Bosbouwmaatschappij","alternateName":"SRFB-KBBM","url":"https:\/\/srfb.be\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/srfb.be\/#\/schema\/logo\/image\/","url":"https:\/\/srfb.be\/wp-content\/uploads\/2019\/06\/android-chrome-256x256.png","contentUrl":"https:\/\/srfb.be\/wp-content\/uploads\/2019\/06\/android-chrome-256x256.png","width":1200,"height":1232,"caption":"Soci\u00e9t\u00e9 Royale Foresti\u00e8re De Belgique - Koninklijke Belgische Bosbouwmaatschappij"},"image":{"@id":"https:\/\/srfb.be\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/srfb.be","https:\/\/www.instagram.com\/srfb_kbbm\/","https:\/\/www.linkedin.com\/company\/srfb-kbbm\/","https:\/\/www.youtube.com\/user\/srfbkbbm"]}]}},"_links":{"self":[{"href":"https:\/\/kbbm.be\/en\/wp-json\/wp\/v2\/srfb-formations\/40064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kbbm.be\/en\/wp-json\/wp\/v2\/srfb-formations"}],"about":[{"href":"https:\/\/kbbm.be\/en\/wp-json\/wp\/v2\/types\/srfb-formations"}],"author":[{"embeddable":true,"href":"https:\/\/kbbm.be\/en\/wp-json\/wp\/v2\/users\/18"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kbbm.be\/en\/wp-json\/wp\/v2\/media\/22247"}],"wp:attachment":[{"href":"https:\/\/kbbm.be\/en\/wp-json\/wp\/v2\/media?parent=40064"}],"wp:term":[{"taxonomy":"event-types","embeddable":true,"href":"https:\/\/kbbm.be\/en\/wp-json\/wp\/v2\/event-types?post=40064"},{"taxonomy":"event-languages","embeddable":true,"href":"https:\/\/kbbm.be\/en\/wp-json\/wp\/v2\/event-languages?post=40064"},{"taxonomy":"srfb-formations-taxonomy","embeddable":true,"href":"https:\/\/kbbm.be\/en\/wp-json\/wp\/v2\/srfb-formations-taxonomy?post=40064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}