{"id":36999,"date":"2024-07-23T09:25:28","date_gmt":"2024-07-23T07:25:28","guid":{"rendered":"https:\/\/srfb.be\/?post_type=product&#038;p=36999"},"modified":"2024-07-23T09:27:14","modified_gmt":"2024-07-23T07:27:14","slug":"jenseits-der-alten-mauer","status":"publish","type":"product","link":"https:\/\/kbbm.be\/de\/forest-shop\/au-dela-du-vieux-mur\/","title":{"rendered":"Jenseits der alten Mauer"},"content":{"rendered":"<p><em>Ich traf den alten Mann am Abend des Sturms. Er kam in seinem verblichenen Blaumann aus dem Schafstall. Als er mich sah, zitternd vor K\u00e4lte und Angst, lud er mich ein, mich im gro\u00dfen Salon des Herrenhauses, im Herzen von Hermelines Anwesen, aufzuw\u00e4rmen.<\/em><\/p>\n<p><em>Als Schlossherr und G\u00e4rtner zugleich h\u00fctete dieser Mann einen Schatz.<\/em><\/p>\n<p>Von den Menschen vergessen, schl\u00e4ft das Anwesen von Hermeline am Rande des Dorfes. In diesem Reich, in dem ein einsamer alter Mann lebt, lernt ein Kind, das Land zu lieben. Es entdeckt den Wert der Stille und der Freundschaft. Skizze einer ausgel\u00f6schten Welt, die vielleicht irgendwo noch existiert.<\/p>","protected":false},"excerpt":{"rendered":"<p><em>Ich traf den alten Mann am Abend des Sturms. Er kam in seinem verblichenen Blaumann aus dem Schafstall. Als er mich sah, zitternd vor K\u00e4lte und Angst, lud er mich ein, mich im gro\u00dfen Salon des Herrenhauses, im Herzen von Hermelines Anwesen, aufzuw\u00e4rmen.<\/em><\/p>\n<p><em>Als Schlossherr und G\u00e4rtner zugleich h\u00fctete dieser Mann einen Schatz.<\/em><\/p>\n<p>Von den Menschen vergessen, schl\u00e4ft das Anwesen von Hermeline am Rande des Dorfes. In diesem Reich, in dem ein einsamer alter Mann lebt, lernt ein Kind, das Land zu lieben. Es entdeckt den Wert der Stille und der Freundschaft. Skizze einer ausgel\u00f6schten Welt, die vielleicht irgendwo noch existiert.<\/p>\n<p>Autorin: <strong>Olivier Terlinden<\/strong><\/p>","protected":false},"featured_media":37000,"comment_status":"closed","ping_status":"closed","template":"","meta":{"iawp_total_views":50},"product_brand":[],"product_cat":[696],"product_tag":[],"class_list":{"0":"post-36999","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-visiteurs","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Au-del\u00e0 du vieux mur - Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kbbm.be\/de\/forest-shop\/jenseits-der-alten-mauer\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Au-del\u00e0 du vieux mur - Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique\" \/>\n<meta property=\"og:description\" content=\"J\u2019ai rencontr\u00e9 le vieil homme le soir de la temp\u00eate. Il sortait de la bergerie dans son bleu de travail d\u00e9color\u00e9. Quand il me vit, grelottant de froid et de peur, il m\u2019invita \u00e0 me r\u00e9chauffer dans le grand salon du manoir, au c\u0153ur du domaine d\u2019Hermeline.  \u00c0 la fois ch\u00e2telain et jardinier, cet homme gardait un tr\u00e9sor.  Oubli\u00e9 des hommes, le domaine d\u2019Hermeline dort en bordure du village. Dans ce royaume o\u00f9 vit un vieillard solitaire, un enfant apprend \u00e0 aimer la terre. Il y d\u00e9couvre la valeur du silence et de l\u2019amiti\u00e9. Esquisse d\u2019un monde effac\u00e9 qui, peut-\u00eatre, quelque part, existe encore.  Auteur : Olivier Terlinden\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kbbm.be\/de\/forest-shop\/jenseits-der-alten-mauer\/\" \/>\n<meta property=\"og:site_name\" content=\"Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/srfb.be\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-23T07:27:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kbbm.be\/wp-content\/uploads\/2024\/07\/Vieux-mur-couverture.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"1207\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kbbm.be\\\/en\\\/forest-shop\\\/beyond-the-old-wall\\\/\",\"url\":\"https:\\\/\\\/kbbm.be\\\/en\\\/forest-shop\\\/beyond-the-old-wall\\\/\",\"name\":\"Au-del\u00e0 du vieux mur - Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/srfb.be\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kbbm.be\\\/en\\\/forest-shop\\\/beyond-the-old-wall\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kbbm.be\\\/en\\\/forest-shop\\\/beyond-the-old-wall\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kbbm.be\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Vieux-mur-couverture.jpg\",\"datePublished\":\"2024-07-23T07:25:28+00:00\",\"dateModified\":\"2024-07-23T07:27:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kbbm.be\\\/en\\\/forest-shop\\\/beyond-the-old-wall\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kbbm.be\\\/en\\\/forest-shop\\\/beyond-the-old-wall\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/kbbm.be\\\/en\\\/forest-shop\\\/beyond-the-old-wall\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kbbm.be\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Vieux-mur-couverture.jpg\",\"contentUrl\":\"https:\\\/\\\/kbbm.be\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Vieux-mur-couverture.jpg\",\"width\":720,\"height\":1207,\"caption\":\"Couverture du livre : au-del\u00e0 du vieux mur\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kbbm.be\\\/en\\\/forest-shop\\\/beyond-the-old-wall\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/srfb.be\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/srfb.be\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Au-del\u00e0 du vieux mur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/srfb.be\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/srfb.be\\\/nl\\\/\",\"name\":\"Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique\",\"description\":\"Au service de la for\u00eat et des forestiers\",\"publisher\":{\"@id\":\"https:\\\/\\\/srfb.be\\\/nl\\\/#organization\"},\"alternateName\":\"SRFB-KBBM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/srfb.be\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/srfb.be\\\/nl\\\/#organization\",\"name\":\"Soci\u00e9t\u00e9 Royale Foresti\u00e8re De Belgique - Koninklijke Belgische Bosbouwmaatschappij\",\"alternateName\":\"SRFB-KBBM\",\"url\":\"https:\\\/\\\/srfb.be\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/srfb.be\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/srfb.be\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/android-chrome-256x256.png\",\"contentUrl\":\"https:\\\/\\\/srfb.be\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/android-chrome-256x256.png\",\"width\":1200,\"height\":1232,\"caption\":\"Soci\u00e9t\u00e9 Royale Foresti\u00e8re De Belgique - Koninklijke Belgische Bosbouwmaatschappij\"},\"image\":{\"@id\":\"https:\\\/\\\/srfb.be\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/srfb.be\",\"https:\\\/\\\/www.instagram.com\\\/srfb_kbbm\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/srfb-kbbm\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/srfbkbbm\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jenseits der alten Mauer - K\u00f6niglich Belgische Forstgesellschaft","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kbbm.be\/de\/forest-shop\/jenseits-der-alten-mauer\/","og_locale":"de_DE","og_type":"article","og_title":"Au-del\u00e0 du vieux mur - Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique","og_description":"J\u2019ai rencontr\u00e9 le vieil homme le soir de la temp\u00eate. Il sortait de la bergerie dans son bleu de travail d\u00e9color\u00e9. Quand il me vit, grelottant de froid et de peur, il m\u2019invita \u00e0 me r\u00e9chauffer dans le grand salon du manoir, au c\u0153ur du domaine d\u2019Hermeline.  \u00c0 la fois ch\u00e2telain et jardinier, cet homme gardait un tr\u00e9sor.  Oubli\u00e9 des hommes, le domaine d\u2019Hermeline dort en bordure du village. Dans ce royaume o\u00f9 vit un vieillard solitaire, un enfant apprend \u00e0 aimer la terre. Il y d\u00e9couvre la valeur du silence et de l\u2019amiti\u00e9. Esquisse d\u2019un monde effac\u00e9 qui, peut-\u00eatre, quelque part, existe encore.  Auteur : Olivier Terlinden","og_url":"https:\/\/kbbm.be\/de\/forest-shop\/jenseits-der-alten-mauer\/","og_site_name":"Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique","article_publisher":"https:\/\/www.facebook.com\/srfb.be","article_modified_time":"2024-07-23T07:27:14+00:00","og_image":[{"width":720,"height":1207,"url":"https:\/\/kbbm.be\/wp-content\/uploads\/2024\/07\/Vieux-mur-couverture.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kbbm.be\/en\/forest-shop\/beyond-the-old-wall\/","url":"https:\/\/kbbm.be\/en\/forest-shop\/beyond-the-old-wall\/","name":"Jenseits der alten Mauer - K\u00f6niglich Belgische Forstgesellschaft","isPartOf":{"@id":"https:\/\/srfb.be\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kbbm.be\/en\/forest-shop\/beyond-the-old-wall\/#primaryimage"},"image":{"@id":"https:\/\/kbbm.be\/en\/forest-shop\/beyond-the-old-wall\/#primaryimage"},"thumbnailUrl":"https:\/\/kbbm.be\/wp-content\/uploads\/2024\/07\/Vieux-mur-couverture.jpg","datePublished":"2024-07-23T07:25:28+00:00","dateModified":"2024-07-23T07:27:14+00:00","breadcrumb":{"@id":"https:\/\/kbbm.be\/en\/forest-shop\/beyond-the-old-wall\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kbbm.be\/en\/forest-shop\/beyond-the-old-wall\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/kbbm.be\/en\/forest-shop\/beyond-the-old-wall\/#primaryimage","url":"https:\/\/kbbm.be\/wp-content\/uploads\/2024\/07\/Vieux-mur-couverture.jpg","contentUrl":"https:\/\/kbbm.be\/wp-content\/uploads\/2024\/07\/Vieux-mur-couverture.jpg","width":720,"height":1207,"caption":"Couverture du livre : au-del\u00e0 du vieux mur"},{"@type":"BreadcrumbList","@id":"https:\/\/kbbm.be\/en\/forest-shop\/beyond-the-old-wall\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/srfb.be\/nl\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/srfb.be\/shop\/"},{"@type":"ListItem","position":3,"name":"Au-del\u00e0 du vieux mur"}]},{"@type":"WebSite","@id":"https:\/\/srfb.be\/nl\/#website","url":"https:\/\/srfb.be\/nl\/","name":"K\u00f6nigliche Forstverein Belgiens","description":"Im Dienste des Waldes und der F\u00f6rster","publisher":{"@id":"https:\/\/srfb.be\/nl\/#organization"},"alternateName":"SRFB-KBBM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/srfb.be\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/srfb.be\/nl\/#organization","name":"Soci\u00e9t\u00e9 Royale Foresti\u00e8re De Belgique - Koninklijke Belgische Bosbouwmaatschappij","alternateName":"SRFB-KBBM","url":"https:\/\/srfb.be\/nl\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/srfb.be\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/srfb.be\/wp-content\/uploads\/2019\/06\/android-chrome-256x256.png","contentUrl":"https:\/\/srfb.be\/wp-content\/uploads\/2019\/06\/android-chrome-256x256.png","width":1200,"height":1232,"caption":"Soci\u00e9t\u00e9 Royale Foresti\u00e8re De Belgique - Koninklijke Belgische Bosbouwmaatschappij"},"image":{"@id":"https:\/\/srfb.be\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/srfb.be","https:\/\/www.instagram.com\/srfb_kbbm\/","https:\/\/www.linkedin.com\/company\/srfb-kbbm\/","https:\/\/www.youtube.com\/user\/srfbkbbm"]}]}},"_links":{"self":[{"href":"https:\/\/kbbm.be\/de\/wp-json\/wp\/v2\/product\/36999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kbbm.be\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/kbbm.be\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/kbbm.be\/de\/wp-json\/wp\/v2\/comments?post=36999"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kbbm.be\/de\/wp-json\/wp\/v2\/media\/37000"}],"wp:attachment":[{"href":"https:\/\/kbbm.be\/de\/wp-json\/wp\/v2\/media?parent=36999"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/kbbm.be\/de\/wp-json\/wp\/v2\/product_brand?post=36999"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/kbbm.be\/de\/wp-json\/wp\/v2\/product_cat?post=36999"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/kbbm.be\/de\/wp-json\/wp\/v2\/product_tag?post=36999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}