{"id":31241,"date":"2023-05-24T13:52:08","date_gmt":"2023-05-24T11:52:08","guid":{"rendered":"https:\/\/srfb.be\/?page_id=31241"},"modified":"2024-09-03T14:29:57","modified_gmt":"2024-09-03T12:29:57","slug":"familien-und-verbandswelt","status":"publish","type":"page","link":"https:\/\/kbbm.be\/de\/forest-friends\/services-et-activites\/familles-et-monde-associatif\/","title":{"rendered":"Familien und Vereinswelt"},"content":{"rendered":"<div class=\"yoast-breadcrumbs\"><span><span><a href=\"https:\/\/srfb.be\/nl\/\">Accueil<\/a><\/span> &gt; <span><a href=\"https:\/\/srfb.be\/forest-friends\/\">D\u00e9couvrez Forest Friends<\/a><\/span> &gt; <span><a href=\"https:\/\/srfb.be\/forest-friends\/services-et-activites\/\">Services et activit\u00e9s<\/a><\/span> &gt; <span class=\"breadcrumb_last\" aria-current=\"page\"><strong>Familles et monde associatif<\/strong><\/span><\/span><\/div>\n\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-5bf74516 wp-block-group-is-layout-constrained\" style=\"margin-top:var(--wp--preset--spacing--80);margin-bottom:var(--wp--preset--spacing--60)\">\n<h2 class=\"wp-block-heading has-vert-fonce-color-color has-text-color has-link-color wp-elements-5e0631230b99ff6b1f61329db8a7ff00\">Balade foresti\u00e8re<\/h2>\n\n\n\n<p><strong>Vous \u00eates membre de la SRFB\u202f?\u202f<\/strong>Vous souhaitez organiser une balade pour votre famille, des amis ou des voisins pour leur faire d\u00e9couvrir votre passion\u202f?&nbsp;<\/p>\n\n\n\n<p><strong>Ou vous \u00eates une asbl<\/strong> et souhaitez r\u00e9aliser une activit\u00e9 pour votre groupe\u202f?&nbsp;<\/p>\n\n\n\n<p>Partez en for\u00eat avec nos Guides Forestiers\u202f! Au-del\u00e0 du d\u00e9cor de promenade, la for\u00eat est source de sant\u00e9, d\u2019oxyg\u00e8ne et de biodiversit\u00e9. Elle contribue au cycle de l\u2019eau et \u00e0 la r\u00e9gulation du climat. Source d\u2019emplois, elle nous procure un mat\u00e9riau noble et chaleureux. Elle est aussi lieu de ressourcement, de calme et de beaut\u00e9, en lien avec notre histoire.&nbsp;<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-cover\" style=\"min-height:350px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1553\" class=\"wp-block-cover__image-background wp-image-24023\" alt=\"forest friends - cover silva 3 2022\" src=\"https:\/\/srfb.be\/wp-content\/uploads\/2022\/05\/Silva-3-2022-HD.jpg\" style=\"object-position:65% 40%\" data-object-fit=\"cover\" data-object-position=\"65% 40%\" srcset=\"https:\/\/kbbm.be\/wp-content\/uploads\/2022\/05\/Silva-3-2022-HD.jpg 1200w, https:\/\/kbbm.be\/wp-content\/uploads\/2022\/05\/Silva-3-2022-HD-600x777.jpg 600w, https:\/\/kbbm.be\/wp-content\/uploads\/2022\/05\/Silva-3-2022-HD-232x300.jpg 232w, https:\/\/kbbm.be\/wp-content\/uploads\/2022\/05\/Silva-3-2022-HD-791x1024.jpg 791w, https:\/\/kbbm.be\/wp-content\/uploads\/2022\/05\/Silva-3-2022-HD-9x12.jpg 9w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<p class=\"has-text-align-center has-large-font-size\"><\/p>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-cover\" style=\"min-height:350px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"1133\" height=\"1700\" class=\"wp-block-cover__image-background wp-image-11048\" alt=\"homme marchant dans la for\u00eat\" src=\"https:\/\/srfb.be\/wp-content\/uploads\/2020\/03\/forest-1147626_1920.jpg\" style=\"object-position:55% 69%\" data-object-fit=\"cover\" data-object-position=\"55% 69%\" srcset=\"https:\/\/kbbm.be\/wp-content\/uploads\/2020\/03\/forest-1147626_1920.jpg 1133w, https:\/\/kbbm.be\/wp-content\/uploads\/2020\/03\/forest-1147626_1920-300x450.jpg 300w, https:\/\/kbbm.be\/wp-content\/uploads\/2020\/03\/forest-1147626_1920-600x900.jpg 600w, https:\/\/kbbm.be\/wp-content\/uploads\/2020\/03\/forest-1147626_1920-200x300.jpg 200w, https:\/\/kbbm.be\/wp-content\/uploads\/2020\/03\/forest-1147626_1920-682x1024.jpg 682w, https:\/\/kbbm.be\/wp-content\/uploads\/2020\/03\/forest-1147626_1920-8x12.jpg 8w\" sizes=\"auto, (max-width: 1133px) 100vw, 1133px\" \/><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<p class=\"has-text-align-center has-large-font-size\"><\/p>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-cover is-light\" style=\"min-height:350px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"1700\" height=\"1275\" class=\"wp-block-cover__image-background wp-image-7867\" alt=\"Formation des guides forestiers\" src=\"https:\/\/srfb.be\/wp-content\/uploads\/2019\/07\/Formation-des-guides-forestiers-scaled.jpg\" style=\"object-position:50% 62%\" data-object-fit=\"cover\" data-object-position=\"50% 62%\" srcset=\"https:\/\/kbbm.be\/wp-content\/uploads\/2019\/07\/Formation-des-guides-forestiers-scaled.jpg 1700w, https:\/\/kbbm.be\/wp-content\/uploads\/2019\/07\/Formation-des-guides-forestiers-scaled-600x450.jpg 600w, https:\/\/kbbm.be\/wp-content\/uploads\/2019\/07\/Formation-des-guides-forestiers-scaled-300x225.jpg 300w, https:\/\/kbbm.be\/wp-content\/uploads\/2019\/07\/Formation-des-guides-forestiers-scaled-1024x768.jpg 1024w, https:\/\/kbbm.be\/wp-content\/uploads\/2019\/07\/Formation-des-guides-forestiers-scaled-16x12.jpg 16w\" sizes=\"auto, (max-width: 1700px) 100vw, 1700px\" \/><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<p class=\"has-text-align-center has-large-font-size\"><\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-722095d7 wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group has-grey-color-background-color has-background is-layout-constrained wp-container-core-group-is-layout-db32e940 wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--60);padding-right:var(--wp--preset--spacing--60);padding-bottom:var(--wp--preset--spacing--60);padding-left:var(--wp--preset--spacing--60)\">\n<h4 class=\"wp-block-heading\">Informations pratiques<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><em>Type d\u2019activit\u00e9 :&nbsp;<\/em>Balade en for\u00eat<\/li>\n\n\n\n<li><em>Dur\u00e9e :\u00a0<\/em>2h-2h30<\/li>\n\n\n\n<li><em>Nombre de participants :\u00a0<\/em>15 participants (pour plus de participants, merci de nous contacter)<\/li>\n\n\n\n<li><em>Tarif :\u00a0<\/em>200 euros HTVA 21%<\/li>\n\n\n\n<li><em>Remarque :\u00a0<\/em>Le lieu de la balade sera fix\u00e9 de commun accord (dans votre for\u00eat ou une for\u00eat accessible pour votre association)<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-02ebdda1 wp-block-group-is-layout-constrained\" style=\"margin-top:var(--wp--preset--spacing--80);margin-bottom:var(--wp--preset--spacing--80)\">\n<h2 class=\"wp-block-heading has-text-align-center\">Contact<\/h2>\n\n\n\n<p class=\"has-text-align-center\"><strong>Julie Goffette&nbsp;&nbsp;<\/strong>| Charg\u00e9e de projet \u00ab Forest Friends \u00bb<br><a href=\"mailto:julie.goffette@srfb-kbbm.be\">julie.goffette@srfb-kbbm.be<\/a><\/p>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-block-group-is-layout-constrained\" style=\"margin-top:var(--wp--preset--spacing--60);margin-bottom:var(--wp--preset--spacing--60);padding-top:0;padding-bottom:0\"><div class='fluentform ff-default fluentform_wrapper_13  ff_guten_block ff_guten_block-13 ffs_custom_wrap'><form data-form_id=\"13\" id=\"fluentform_13\" class=\"frm-fluent-form fluent_form_13 ff-el-form-top ff_form_instance_13_1 ff-form-loading ff_has_v3_recptcha ffs_custom\" data-form_instance=\"ff_form_instance_13_1\" method=\"POST\" data-recptcha_key=\"6Le57_caAAAAAONi-tUbBRgh8pY4WFvTwsva_Nwx\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">Demandes personnalis\u00e9es<\/legend><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"ak_\"><label>&#916;<textarea name=\"ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"ak_js\" value=\"197\"\/><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n\/* ]]> *\/\n<\/script>\n<\/p><input type='hidden' name='__fluent_form_embded_post_id' value='31241' \/><input type=\"hidden\" id=\"_fluentform_13_fluentformnonce\" name=\"_fluentform_13_fluentformnonce\" value=\"eac2113819\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/de\/wp-json\/wp\/v2\/pages\/31241\" \/><div class='ff-el-group has-conditions'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_13_hectar_number' id='label_ff_13_hectar_number' aria-label=\"Combien d&#039;hectar avez-vous ?\">Combien d&rsquo;hectar avez-vous ?<\/label><\/div><div class='ff-el-input--content'><input type=\"number\" name=\"hectar_number\" value=\"1\" id=\"ff_13_hectar_number\" class=\"ff-el-form-control\" data-name=\"hectar_number\" inputmode=\"numeric\" step=\"any\" min=\"1\" aria-valuemin=\"1\"  aria-invalid=\"false\" aria-required=true><\/div><\/div><div data-type=\"name-element\" data-name=\"names\" class=\" ff-field_container ff-name-field-wrapper\" ><div class='ff-t-container'><div class='ff-t-cell '><div class='ff-el-group  ff-el-form-top'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_13_names_first_name_' id='label_ff_13_names_first_name_' >Pr\u00e9nom<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"names[first_name]\" value=\"\" id=\"ff_13_names_first_name_\" class=\"ff-el-form-control\" placeholder=\"Pr\u00e9nom\" aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><div class='ff-t-cell '><div class='ff-el-group  ff-el-form-top'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_13_names_last_name_' id='label_ff_13_names_last_name_' >Nom de famille<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"names[last_name]\" value=\"\" id=\"ff_13_names_last_name_\" class=\"ff-el-form-control\" placeholder=\"Nom de famille\" aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><\/div><\/div><div data-name=\"ff_cn_id_1\"  class='ff-t-container ff-column-container ff_columns_total_2 '><div class='ff-t-cell ff-t-column-1' style='flex-basis: 50%;'><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_13_email' id='label_ff_13_email' aria-label=\"E-mail\">E-mail<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email\" value=\"\" id=\"ff_13_email\" class=\"ff-el-form-control\" placeholder=\"info@srfb-kbbm.be\" data-name=\"email\"  aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><div class='ff-t-cell ff-t-column-2' style='flex-basis: 50%;'><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_13_phone' id='label_ff_13_phone' aria-label=\"T\u00e9l\u00e9phone\">T\u00e9l\u00e9phone<\/label><\/div><div class='ff-el-input--content'><input name=\"phone\" class=\"ff-el-form-control ff-el-phone ff_el_with_extended_validation\" type=\"tel\" placeholder=\"Num\u00e9ro de portable\" data-name=\"phone\" id=\"ff_13_phone\" inputmode=\"tel\"  aria-invalid='false' aria-required=false><\/div><\/div><\/div><\/div><div class='ff-el-group center ff_list_buttons'><div class=\"ff-el-input--label asterisk-right\"><label   aria-label=\"Je suis membre ...\">Je suis membre &#8230;<\/label><div class=\"ff-el-tooltip\" data-content=\"Choix multiple possible\"><svg width=\"16\" height=\"16\" viewBox=\"0 0 25 25\"><path d=\"m329 393l0-46c0-2-1-4-2-6-2-2-4-3-7-3l-27 0 0-146c0-3-1-5-3-7-2-1-4-2-7-2l-91 0c-3 0-5 1-7 2-1 2-2 4-2 7l0 46c0 2 1 5 2 6 2 2 4 3 7 3l27 0 0 91-27 0c-3 0-5 1-7 3-1 2-2 4-2 6l0 46c0 3 1 5 2 7 2 1 4 2 7 2l128 0c3 0 5-1 7-2 1-2 2-4 2-7z m-36-256l0-46c0-2-1-4-3-6-2-2-4-3-7-3l-54 0c-3 0-5 1-7 3-2 2-3 4-3 6l0 46c0 3 1 5 3 7 2 1 4 2 7 2l54 0c3 0 5-1 7-2 2-2 3-4 3-7z m182 119c0 40-9 77-29 110-20 34-46 60-80 80-33 20-70 29-110 29-40 0-77-9-110-29-34-20-60-46-80-80-20-33-29-70-29-110 0-40 9-77 29-110 20-34 46-60 80-80 33-20 70-29 110-29 40 0 77 9 110 29 34 20 60 46 80 80 20 33 29 70 29 110z\" transform=\"scale(0.046875 0.046875)\"><\/path><\/svg><\/div><\/div><div class='ff-el-input--content'><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_830d9c71bf402f0ccd7c3423dbf24419'><input  type=\"checkbox\" name=\"checkbox[]\" data-name=\"checkbox\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"SRFB\"  id='checkbox_830d9c71bf402f0ccd7c3423dbf24419' aria-label='SRFB' aria-invalid='false' aria-required=false> <span>SRFB<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_852d79f1b44e600cdcbaded0a39801fa'><input  type=\"checkbox\" name=\"checkbox[]\" data-name=\"checkbox\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"NTF\"  id='checkbox_852d79f1b44e600cdcbaded0a39801fa' aria-label='NTF' aria-invalid='false' aria-required=false> <span>NTF<\/span><\/label><\/div><div class='ff-el-form-check ff-el-form-check-'><label class='ff-el-form-check-label' for='checkbox_c83abd81b4380a0ac465e4cedabb95e5'><input  type=\"checkbox\" name=\"checkbox[]\" data-name=\"checkbox\" class=\"ff-el-form-check-input ff-el-form-check-checkbox\" value=\"LV\"  id='checkbox_c83abd81b4380a0ac465e4cedabb95e5' aria-label='LV' aria-invalid='false' aria-required=false> <span>LV<\/span><\/label><\/div><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_13_message' id='label_ff_13_message' aria-label=\"R\u00e9digez votre demande\">R\u00e9digez votre demande<\/label><\/div><div class='ff-el-input--content'><textarea aria-required=\"true\" aria-labelledby=\"label_ff_13_message\" name=\"message\" id=\"ff_13_message\" class=\"ff-el-form-control\" placeholder=\"R\u00e9digez votre demande...\" rows=\"5\" cols=\"2\" data-name=\"message\" ><\/textarea><\/div><\/div><div class='ff-el-group  ff-custom_html' tabindex='-1' data-name=\"custom_html-13_1\" ><p><i>En nous envoyant votre demande, vous affirmez avoir lu et acceptez la <a href=\"https:\/\/srfb.be\/declaration-de-confidentialite\" target=\"_blank\" rel=\"noopener\">d\u00e9claration de confidentialit\u00e9<\/a>\u00a0et \u00eates conscient d&rsquo;avoir le droit \u00e0 tout moment de vous r\u00e9tracter en faisant part de votre d\u00e9cision \u00e0 la SRFB Boulevard Bischoffsheim, 1-8 \u00e0 1000 Bruxelles ou par mail \u00e0\u00a0<a id=\"OWAb79d679b-bcaa-5714-6911-22a5d7fae149\" class=\"x_OWAAutoLink\" title=\"mailto:secretariat@srfb-kbbm.be\" href=\"mailto:secretariat@srfb-kbbm.be\" data-linkindex=\"2\">secretariat@srfb-kbbm.be<\/a><\/i><\/p><\/div><div class='ff-el-group ff-text-right bold ff_submit_btn_wrapper ff_submit_btn_wrapper_custom'><button class=\"ff-btn ff-btn-submit ff-btn-md ff_btn_style\" type=\"submit\" name=\"custom_submit_button-13_2\" data-name=\"custom_submit_button-13_2\"  aria-label=\"Envoyer\">Envoyer<\/button><style>form.fluent_form_13 .ff-btn-submit { background-color: #1a7efb; color: #ffffff; }<\/style><\/div><input type=\"hidden\" name=\"post_id\" value=\"31241\" data-name=\"post_id\" ><\/fieldset><\/form><div id='fluentform_13_errors' class='ff-errors-in-stack ff_form_instance_13_1 ff-form-loading_errors ff_form_instance_13_1_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_13_1 = {\"id\":\"13\",\"ajaxUrl\":\"https:\\\/\\\/kbbm.be\\\/wp-admin\\\/admin-ajax.php\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"asteriskPlacement\":\"asterisk-right\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_13_1\",\"form_id_selector\":\"fluentform_13\",\"rules\":{\"hectar_number\":{\"required\":{\"value\":true,\"message\":\"Ce champ est obligatoire\",\"global\":false,\"global_message\":\"Ce champ est obligatoire\"},\"numeric\":{\"value\":true,\"message\":\"Ce champ doit contenir une valeur num\\u00e9rique\",\"global\":false,\"global_message\":\"Ce champ doit contenir une valeur num\\u00e9rique\"},\"min\":{\"value\":\"1\",\"message\":\"Valeur minimale est \",\"global\":false,\"global_message\":\"La validation \\u00e9choue pour la valeur minimale\"},\"max\":{\"value\":\"\",\"message\":\"Valeur maximale est \",\"global\":false,\"global_message\":\"La validation \\u00e9choue pour la valeur maximale\"},\"digits\":{\"value\":\"\",\"message\":\"Le nombre de chiffres doit \\u00eatre \",\"global\":false,\"global_message\":\"La validation \\u00e9choue pour les chiffres limit\\u00e9s\"}},\"names[first_name]\":{\"required\":{\"value\":true,\"message\":\"Ce champ est obligatoire\",\"global\":false,\"global_message\":\"Ce champ est obligatoire\"}},\"names[middle_name]\":{\"required\":{\"value\":false,\"message\":\"Ce champ est obligatoire\",\"global\":false,\"global_message\":\"Ce champ est obligatoire\"}},\"names[last_name]\":{\"required\":{\"value\":true,\"message\":\"Ce champ est obligatoire\",\"global\":false,\"global_message\":\"Ce champ est obligatoire\"}},\"email\":{\"required\":{\"value\":true,\"message\":\"Ce champ est obligatoire\",\"global\":false,\"global_message\":\"Ce champ est obligatoire\"},\"email\":{\"value\":true,\"message\":\"Ce champ doit contenir un e-mail valide\",\"global\":false,\"global_message\":\"Ce champ doit contenir un courriel valide\"}},\"phone\":{\"required\":{\"value\":false,\"message\":\"Ce champ est requis\",\"global\":false,\"global_message\":\"Ce champ est obligatoire\"},\"valid_phone_number\":{\"value\":true,\"message\":\"Le num\\u00e9ro de t\\u00e9l\\u00e9phone n'est pas valide\",\"global\":false,\"global_message\":\"Le num\\u00e9ro de t\\u00e9l\\u00e9phone n\\u2019est pas valide\"}},\"checkbox\":{\"required\":{\"value\":false,\"message\":\"Ce champ est obligatoire\",\"global\":false,\"global_message\":\"Ce champ est obligatoire\"}},\"message\":{\"required\":{\"value\":true,\"message\":\"Ce champ est obligatoire\",\"global\":false,\"global_message\":\"Ce champ est obligatoire\"}},\"g-recaptcha-response\":[]},\"debounce_time\":300,\"conditionals\":{\"hectar_number\":{\"type\":\"any\",\"status\":true,\"conditions\":[{\"field\":\"post_id\",\"value\":\"11918\",\"operator\":\"=\"},{\"field\":\"post_id\",\"value\":\"7906\",\"operator\":\"=\"}]}}};\n                            <\/script>\n            <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Balade foresti\u00e8re Vous \u00eates membre de la SRFB\u202f?\u202fVous souhaitez organiser une balade pour votre famille, des amis ou des voisins pour leur faire d\u00e9couvrir votre passion\u202f?&nbsp; Ou vous \u00eates une asbl et souhaitez r\u00e9aliser une activit\u00e9 pour votre groupe\u202f?&nbsp; Partez en for\u00eat avec nos Guides Forestiers\u202f! Au-del\u00e0 du d\u00e9cor de promenade, la for\u00eat est source&#8230; <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/kbbm.be\/de\/forest-friends\/services-et-activites\/familles-et-monde-associatif\/\" class=\"excerpt-read-more\">Read More<\/a><\/p>","protected":false},"author":18,"featured_media":24023,"parent":15904,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"iawp_total_views":80,"footnotes":""},"class_list":["post-31241","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Familles et monde associatif | Forest Friends - SRFB<\/title>\n<meta name=\"description\" content=\"Partez en for\u00eat avec nos Guides Forestiers ! Au-del\u00e0 du d\u00e9cor de promenade, la for\u00eat est source de sant\u00e9, d\u2019oxyg\u00e8ne et de biodiversit\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/srfb.be\/forest-friends\/services-et-activites\/familles-et-monde-associatif\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Familles et monde associatif | Forest Friends - SRFB\" \/>\n<meta property=\"og:description\" content=\"Partez en for\u00eat avec nos Guides Forestiers ! Au-del\u00e0 du d\u00e9cor de promenade, la for\u00eat est source de sant\u00e9, d\u2019oxyg\u00e8ne et de biodiversit\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/srfb.be\/forest-friends\/services-et-activites\/familles-et-monde-associatif\/\" \/>\n<meta property=\"og:site_name\" content=\"Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/srfb.be\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-03T12:29:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/srfb.be\/wp-content\/uploads\/2022\/05\/Silva-3-2022-HD.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1553\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/srfb.be\\\/forest-friends\\\/services-et-activites\\\/familles-et-monde-associatif\\\/\",\"url\":\"https:\\\/\\\/srfb.be\\\/forest-friends\\\/services-et-activites\\\/familles-et-monde-associatif\\\/\",\"name\":\"Familles et monde associatif | Forest Friends - SRFB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/srfb.be\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/srfb.be\\\/forest-friends\\\/services-et-activites\\\/familles-et-monde-associatif\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/srfb.be\\\/forest-friends\\\/services-et-activites\\\/familles-et-monde-associatif\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kbbm.be\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Silva-3-2022-HD.jpg\",\"datePublished\":\"2023-05-24T11:52:08+00:00\",\"dateModified\":\"2024-09-03T12:29:57+00:00\",\"description\":\"Partez en for\u00eat avec nos Guides Forestiers ! Au-del\u00e0 du d\u00e9cor de promenade, la for\u00eat est source de sant\u00e9, d\u2019oxyg\u00e8ne et de biodiversit\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/srfb.be\\\/forest-friends\\\/services-et-activites\\\/familles-et-monde-associatif\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/srfb.be\\\/forest-friends\\\/services-et-activites\\\/familles-et-monde-associatif\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/srfb.be\\\/forest-friends\\\/services-et-activites\\\/familles-et-monde-associatif\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kbbm.be\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Silva-3-2022-HD.jpg\",\"contentUrl\":\"https:\\\/\\\/kbbm.be\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Silva-3-2022-HD.jpg\",\"width\":1200,\"height\":1553,\"caption\":\"forest friends - cover silva 3 2022\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/srfb.be\\\/forest-friends\\\/services-et-activites\\\/familles-et-monde-associatif\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/srfb.be\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00e9couvrez Forest Friends\",\"item\":\"https:\\\/\\\/srfb.be\\\/forest-friends\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Services et activit\u00e9s\",\"item\":\"https:\\\/\\\/srfb.be\\\/forest-friends\\\/services-et-activites\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Familles et monde associatif\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/srfb.be\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/srfb.be\\\/nl\\\/\",\"name\":\"Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique\",\"description\":\"Au service de la for\u00eat et des forestiers\",\"publisher\":{\"@id\":\"https:\\\/\\\/srfb.be\\\/nl\\\/#organization\"},\"alternateName\":\"SRFB-KBBM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/srfb.be\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/srfb.be\\\/nl\\\/#organization\",\"name\":\"Soci\u00e9t\u00e9 Royale Foresti\u00e8re De Belgique - Koninklijke Belgische Bosbouwmaatschappij\",\"alternateName\":\"SRFB-KBBM\",\"url\":\"https:\\\/\\\/srfb.be\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/srfb.be\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/srfb.be\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/android-chrome-256x256.png\",\"contentUrl\":\"https:\\\/\\\/srfb.be\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/android-chrome-256x256.png\",\"width\":1200,\"height\":1232,\"caption\":\"Soci\u00e9t\u00e9 Royale Foresti\u00e8re De Belgique - Koninklijke Belgische Bosbouwmaatschappij\"},\"image\":{\"@id\":\"https:\\\/\\\/srfb.be\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/srfb.be\",\"https:\\\/\\\/www.instagram.com\\\/srfb_kbbm\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/srfb-kbbm\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/srfbkbbm\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Familien und Vereinswelt | Forest Friends - SRFB","description":"Gehen Sie mit unseren Waldf\u00fchrern in den Wald! Der Wald ist nicht nur eine sch\u00f6ne Kulisse f\u00fcr Spazierg\u00e4nge, sondern auch eine Quelle der Gesundheit, des Sauerstoffs und der Artenvielfalt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/srfb.be\/forest-friends\/services-et-activites\/familles-et-monde-associatif\/","og_locale":"de_DE","og_type":"article","og_title":"Familles et monde associatif | Forest Friends - SRFB","og_description":"Partez en for\u00eat avec nos Guides Forestiers ! Au-del\u00e0 du d\u00e9cor de promenade, la for\u00eat est source de sant\u00e9, d\u2019oxyg\u00e8ne et de biodiversit\u00e9.","og_url":"https:\/\/srfb.be\/forest-friends\/services-et-activites\/familles-et-monde-associatif\/","og_site_name":"Soci\u00e9t\u00e9 Royale Foresti\u00e8re de Belgique","article_publisher":"https:\/\/www.facebook.com\/srfb.be","article_modified_time":"2024-09-03T12:29:57+00:00","og_image":[{"width":1200,"height":1553,"url":"https:\/\/srfb.be\/wp-content\/uploads\/2022\/05\/Silva-3-2022-HD.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/srfb.be\/forest-friends\/services-et-activites\/familles-et-monde-associatif\/","url":"https:\/\/srfb.be\/forest-friends\/services-et-activites\/familles-et-monde-associatif\/","name":"Familien und Vereinswelt | Forest Friends - SRFB","isPartOf":{"@id":"https:\/\/srfb.be\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/srfb.be\/forest-friends\/services-et-activites\/familles-et-monde-associatif\/#primaryimage"},"image":{"@id":"https:\/\/srfb.be\/forest-friends\/services-et-activites\/familles-et-monde-associatif\/#primaryimage"},"thumbnailUrl":"https:\/\/kbbm.be\/wp-content\/uploads\/2022\/05\/Silva-3-2022-HD.jpg","datePublished":"2023-05-24T11:52:08+00:00","dateModified":"2024-09-03T12:29:57+00:00","description":"Gehen Sie mit unseren Waldf\u00fchrern in den Wald! Der Wald ist nicht nur eine sch\u00f6ne Kulisse f\u00fcr Spazierg\u00e4nge, sondern auch eine Quelle der Gesundheit, des Sauerstoffs und der Artenvielfalt.","breadcrumb":{"@id":"https:\/\/srfb.be\/forest-friends\/services-et-activites\/familles-et-monde-associatif\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/srfb.be\/forest-friends\/services-et-activites\/familles-et-monde-associatif\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/srfb.be\/forest-friends\/services-et-activites\/familles-et-monde-associatif\/#primaryimage","url":"https:\/\/kbbm.be\/wp-content\/uploads\/2022\/05\/Silva-3-2022-HD.jpg","contentUrl":"https:\/\/kbbm.be\/wp-content\/uploads\/2022\/05\/Silva-3-2022-HD.jpg","width":1200,"height":1553,"caption":"forest friends - cover silva 3 2022"},{"@type":"BreadcrumbList","@id":"https:\/\/srfb.be\/forest-friends\/services-et-activites\/familles-et-monde-associatif\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/srfb.be\/nl\/"},{"@type":"ListItem","position":2,"name":"D\u00e9couvrez Forest Friends","item":"https:\/\/srfb.be\/forest-friends\/"},{"@type":"ListItem","position":3,"name":"Services et activit\u00e9s","item":"https:\/\/srfb.be\/forest-friends\/services-et-activites\/"},{"@type":"ListItem","position":4,"name":"Familles et monde associatif"}]},{"@type":"WebSite","@id":"https:\/\/srfb.be\/nl\/#website","url":"https:\/\/srfb.be\/nl\/","name":"K\u00f6nigliche Forstverein Belgiens","description":"Im Dienste des Waldes und der F\u00f6rster","publisher":{"@id":"https:\/\/srfb.be\/nl\/#organization"},"alternateName":"SRFB-KBBM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/srfb.be\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/srfb.be\/nl\/#organization","name":"Soci\u00e9t\u00e9 Royale Foresti\u00e8re De Belgique - Koninklijke Belgische Bosbouwmaatschappij","alternateName":"SRFB-KBBM","url":"https:\/\/srfb.be\/nl\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/srfb.be\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/srfb.be\/wp-content\/uploads\/2019\/06\/android-chrome-256x256.png","contentUrl":"https:\/\/srfb.be\/wp-content\/uploads\/2019\/06\/android-chrome-256x256.png","width":1200,"height":1232,"caption":"Soci\u00e9t\u00e9 Royale Foresti\u00e8re De Belgique - Koninklijke Belgische Bosbouwmaatschappij"},"image":{"@id":"https:\/\/srfb.be\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/srfb.be","https:\/\/www.instagram.com\/srfb_kbbm\/","https:\/\/www.linkedin.com\/company\/srfb-kbbm\/","https:\/\/www.youtube.com\/user\/srfbkbbm"]}]}},"_links":{"self":[{"href":"https:\/\/kbbm.be\/de\/wp-json\/wp\/v2\/pages\/31241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kbbm.be\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kbbm.be\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kbbm.be\/de\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/kbbm.be\/de\/wp-json\/wp\/v2\/comments?post=31241"}],"version-history":[{"count":0,"href":"https:\/\/kbbm.be\/de\/wp-json\/wp\/v2\/pages\/31241\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/kbbm.be\/de\/wp-json\/wp\/v2\/pages\/15904"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kbbm.be\/de\/wp-json\/wp\/v2\/media\/24023"}],"wp:attachment":[{"href":"https:\/\/kbbm.be\/de\/wp-json\/wp\/v2\/media?parent=31241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}